{"id":9799,"date":"2025-12-01T09:08:00","date_gmt":"2025-12-01T08:08:00","guid":{"rendered":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/?p=9799"},"modified":"2026-05-06T10:15:03","modified_gmt":"2026-05-06T08:15:03","slug":"natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion","status":"publish","type":"post","link":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html","title":{"rendered":"Nat\u00fcrlich dreisprachig durch den Advent in unserer Dreil\u00e4nderregion!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Gestern ist auf den Adventskr\u00e4nzen die erste Kerze entz\u00fcndet worden. Der Advent h\u00e4lt Einzug in unseren H\u00e4usern und Herzen. Mit ihm beginnt auf\u2018s Neue eine besondere Zeit, die gef\u00fcllt ist mit Vorfreude, Neugier und Magie f\u00fcr Klein bis Gro\u00df. Weihnachten klopft an die T\u00fcr und wartet mit vielen kulturellen Sch\u00e4tzen auf, die sich u. a. in Speisen, Liedern, Gedichten, Geschichten und Br\u00e4uchen entdecken lassen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Dreil\u00e4nderregion zwischen Sachsen, Polen und Tschechien gibt es die M\u00f6glichkeit, gleichzeitig in drei Advents- und Weihnachtskulturen zu blicken und gemeinsam mit den Kindern noch mehr Sch\u00e4tze zu heben.\u00a0<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Die eigenen Traditionen sind uns meist vertraut. Aber wie sieht es im Advent bei unseren Nachbarinnen und Nachbarn in Polen und Tschechien aus?&nbsp;<em>Was<\/em>&nbsp;wird dort&nbsp;<em>wann<\/em>,&nbsp;<em>wie<\/em>&nbsp;und vor allem auch&nbsp;<em>warum<\/em>&nbsp;an Brauchtum gepflegt?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Haben Sie Lust, zusammen mit Ihren Kindern in der Kita, Schule und zu Hause einen Blick auf die Traditionen in den Nachbarl\u00e4ndern zu werfen, diese zu erforschen und auszuprobieren? &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die LaNa bietet Ihnen Anregungen und Umsetzungsideen f\u00fcr eine polnische oder tschechische Adventszeit: Gemeinsam mit Studierenden der&nbsp;<a href=\"https:\/\/www.hszg.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hochschule Zittau\/G\u00f6rlitz<\/a>&nbsp;sind zwei Materialsets entstanden, die Sie kostenlos nutzen k\u00f6nnen. Mit dabei sind die drei Freunde der LaNa:&nbsp;<strong>Mit Biedronka, Maus und \u017d\u00e1ba durch die Adventszeit&nbsp;in Polen&nbsp;<\/strong>bzw<strong>. in Tschechien<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese nehmen Sie mit auf eine ganz besondere Entdeckungsreise durch die Adventszeit in unserer Dreil\u00e4nderregion. Es erwartet Sie und Ihre Kinder eine fortf\u00fchrende Geschichte zum Vorlesen sowie passender Wortschatz, au\u00dferdem Anregungen f\u00fcr Mitmach-Angebote und zahlreiche p\u00e4dagogische Hinweise und weiterf\u00fchrende Informationen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Die Materialien gibt es in den Sprachen Deutsch, Polnisch und Tschechisch unter&nbsp;<a href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/advent\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.nachbarsprachen-sachsen.eu\/advent<\/a>.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dreisprachiger Advent auch f\u00fcr zu Hause?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Na klar, drucken Sie sich gern die Unterlagen f\u00fcr die Adventszeit aus und gehen Sie mit Ihren Kindern oder Enkelkindern zu Hause auf Entdeckungsreise, singen und basteln Sie gemeinsam und probieren Sie die eine oder andere Leckerei aus. Vielleicht haben Sie auch die M\u00f6glichkeit, gemeinsam mit Ihren Freunden aus Polen und Tschechien die Adventszeit zu genie\u00dfen? Dann ist unser Material ein guter Begleiter.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gestern ist auf den Adventskr\u00e4nzen die erste Kerze entz\u00fcndet worden. Der Advent h\u00e4lt Einzug in unseren H\u00e4usern und Herzen. Mit ihm beginnt auf\u2018s Neue eine besondere Zeit, die gef\u00fcllt ist mit Vorfreude, Neugier und Magie f\u00fcr Klein bis Gro\u00df. Weihnachten klopft an die T\u00fcr und wartet mit vielen kulturellen Sch\u00e4tzen auf, die sich u. a. &hellip; <a href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html\" class=\"more-link\"><span class=\"screen-reader-text\">Nat\u00fcrlich dreisprachig durch den Advent in unserer Dreil\u00e4nderregion!<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":9800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3,4,1007],"tags":[1431,780,838,6,1978,30,9,31,1702],"class_list":["post-9799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-eltern","category-kitas","category-materialien","tag-advent","tag-dreilaenderregion","tag-dreisprachig","tag-nachbarsprache","tag-nl4-25","tag-polen","tag-sachsen","tag-tschechien","tag-weihnachtszeit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nat\u00fcrlich dreisprachig durch den Advent in unserer Dreil\u00e4nderregion! - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung<\/title>\n<meta name=\"description\" content=\"Kinder aufgepasst: Mit den drei Freunden der LaNa k\u00f6nnt ihr prima dreisprachig im Advent unterwegs sein und Sch\u00e4tze heben. Los geht&#039;s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nat\u00fcrlich dreisprachig durch den Advent in unserer Dreil\u00e4nderregion! - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\" \/>\n<meta property=\"og:description\" content=\"Kinder aufgepasst: Mit den drei Freunden der LaNa k\u00f6nnt ihr prima dreisprachig im Advent unterwegs sein und Sch\u00e4tze heben. Los geht&#039;s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html\" \/>\n<meta property=\"og:site_name\" content=\"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-01T08:08:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T08:15:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2025\/11\/advent.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"234\" \/>\n\t<meta property=\"og:image:height\" content=\"166\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LaNa-Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"LaNa-Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/materialien\\\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/materialien\\\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html\"},\"author\":{\"name\":\"LaNa-Team\",\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/#\\\/schema\\\/person\\\/13239f936c7ffee5b60975f82a2531a2\"},\"headline\":\"Nat\u00fcrlich dreisprachig durch den Advent in unserer Dreil\u00e4nderregion!\",\"datePublished\":\"2025-12-01T08:08:00+00:00\",\"dateModified\":\"2026-05-06T08:15:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/materialien\\\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html\"},\"wordCount\":386,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/materialien\\\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/advent.jpg\",\"keywords\":[\"Advent\",\"Dreil\u00e4nderregion\",\"dreisprachig\",\"Nachbarsprache\",\"NL4-25\",\"Polen\",\"Sachsen\",\"Tschechien\",\"Weihnachtszeit\"],\"articleSection\":{\"1\":\"Eltern\",\"2\":\"Kitas\",\"3\":\"Materialien\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/materialien\\\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/materialien\\\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html\",\"url\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/materialien\\\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html\",\"name\":\"Nat\u00fcrlich dreisprachig durch den Advent in unserer Dreil\u00e4nderregion! - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/materialien\\\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/materialien\\\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/advent.jpg\",\"datePublished\":\"2025-12-01T08:08:00+00:00\",\"dateModified\":\"2026-05-06T08:15:03+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/#\\\/schema\\\/person\\\/13239f936c7ffee5b60975f82a2531a2\"},\"description\":\"Kinder aufgepasst: Mit den drei Freunden der LaNa k\u00f6nnt ihr prima dreisprachig im Advent unterwegs sein und Sch\u00e4tze heben. Los geht's.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/materialien\\\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/materialien\\\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/materialien\\\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#primaryimage\",\"url\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/advent.jpg\",\"contentUrl\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/advent.jpg\",\"width\":234,\"height\":166},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/materialien\\\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nat\u00fcrlich dreisprachig durch den Advent in unserer Dreil\u00e4nderregion!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/\",\"name\":\"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\",\"description\":\"Nachbarsprache von Anfang an!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/#\\\/schema\\\/person\\\/13239f936c7ffee5b60975f82a2531a2\",\"name\":\"LaNa-Team\",\"url\":\"https:\\\/\\\/www.nachbarsprachen-sachsen.eu\\\/lana\\\/blog\\\/author\\\/ikp-redakteur_ab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nat\u00fcrlich dreisprachig durch den Advent in unserer Dreil\u00e4nderregion! - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","description":"Kinder aufgepasst: Mit den drei Freunden der LaNa k\u00f6nnt ihr prima dreisprachig im Advent unterwegs sein und Sch\u00e4tze heben. Los geht's.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html","og_locale":"de_DE","og_type":"article","og_title":"Nat\u00fcrlich dreisprachig durch den Advent in unserer Dreil\u00e4nderregion! - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","og_description":"Kinder aufgepasst: Mit den drei Freunden der LaNa k\u00f6nnt ihr prima dreisprachig im Advent unterwegs sein und Sch\u00e4tze heben. Los geht's.","og_url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html","og_site_name":"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","article_published_time":"2025-12-01T08:08:00+00:00","article_modified_time":"2026-05-06T08:15:03+00:00","og_image":[{"width":234,"height":166,"url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2025\/11\/advent.jpg","type":"image\/jpeg"}],"author":"LaNa-Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"LaNa-Team","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#article","isPartOf":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html"},"author":{"name":"LaNa-Team","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2"},"headline":"Nat\u00fcrlich dreisprachig durch den Advent in unserer Dreil\u00e4nderregion!","datePublished":"2025-12-01T08:08:00+00:00","dateModified":"2026-05-06T08:15:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html"},"wordCount":386,"commentCount":0,"image":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#primaryimage"},"thumbnailUrl":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2025\/11\/advent.jpg","keywords":["Advent","Dreil\u00e4nderregion","dreisprachig","Nachbarsprache","NL4-25","Polen","Sachsen","Tschechien","Weihnachtszeit"],"articleSection":{"1":"Eltern","2":"Kitas","3":"Materialien"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html","name":"Nat\u00fcrlich dreisprachig durch den Advent in unserer Dreil\u00e4nderregion! - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","isPartOf":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#primaryimage"},"image":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#primaryimage"},"thumbnailUrl":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2025\/11\/advent.jpg","datePublished":"2025-12-01T08:08:00+00:00","dateModified":"2026-05-06T08:15:03+00:00","author":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2"},"description":"Kinder aufgepasst: Mit den drei Freunden der LaNa k\u00f6nnt ihr prima dreisprachig im Advent unterwegs sein und Sch\u00e4tze heben. Los geht's.","breadcrumb":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#primaryimage","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2025\/11\/advent.jpg","contentUrl":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2025\/11\/advent.jpg","width":234,"height":166},{"@type":"BreadcrumbList","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/natuerlich-dreisprachig-durch-den-advent-in-unserer-dreilaenderregion.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog"},{"@type":"ListItem","position":2,"name":"Nat\u00fcrlich dreisprachig durch den Advent in unserer Dreil\u00e4nderregion!"}]},{"@type":"WebSite","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/","name":"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","description":"Nachbarsprache von Anfang an!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2","name":"LaNa-Team","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/author\/ikp-redakteur_ab"}]}},"jetpack_featured_media_url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2025\/11\/advent.jpg","_links":{"self":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts\/9799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/comments?post=9799"}],"version-history":[{"count":1,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts\/9799\/revisions"}],"predecessor-version":[{"id":9801,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts\/9799\/revisions\/9801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/media\/9800"}],"wp:attachment":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/media?parent=9799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/categories?post=9799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/tags?post=9799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}