{"id":9450,"date":"2025-07-30T09:07:56","date_gmt":"2025-07-30T07:07:56","guid":{"rendered":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/?p=9450"},"modified":"2026-05-05T15:25:44","modified_gmt":"2026-05-05T13:25:44","slug":"lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co","status":"publish","type":"post","link":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html","title":{"rendered":"Lecker \u2013 Schmecker No.5: Sommerliche Rezepte aus der LaNa f\u00fcr Gartenfest &amp; Co., heute von unserer Kollegin Michaela"},"content":{"rendered":"\n<p>Getreu dem Motto \u201eSommer, Sonne, Ferien- und Urlaubszeit\u201c hat sich das Team der LaNa eine kleine Beitragsserie f\u00fcr die kommende Zeit ausgedacht: Wir stellen euch jede Woche ein unkompliziertes und obendrein sehr leckeres, sommerliches Rezept vor.<br>Gedacht sind Speis und Trank f\u00fcr Klein bis Gro\u00df. Dar\u00fcber hinaus sind sie auf Tauglichkeit getestet, z. B. f\u00fcr die Sommerfete zu Hause, zum Picknicken am See, als Mitbringsel f\u00fcr einen Besuch bei Freunden im Nachbarland, \u2026 Als Sonderbeilage bringt jedes Rezept einen passenden <strong>Sommerwortschatz in den Nachbarsprachen<\/strong> mit. Habt ihr Lust bekommen? Dann auf die L\u00f6ffel, fertig, ran an die T\u00f6pfe!<\/p>\n\n\n\n<p><strong>Heute im Angebot: <strong>Altb\u00f6hmische knusprige Kartoffelpuffer mit Sauerkraut \u2013 Staroczeskie chrupi\u0105ce placki ziemniaczane z kiszon\u0105 kapust\u0105 \u2013 Staro\u010desk\u00e9 k\u0159upav\u00e9 brambor\u00e1ky s&nbsp;kysel\u00fdm zel\u00edm<\/strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Zubereitungszeit:<\/strong> 60 Minuten<\/li>\n\n\n\n<li><strong>Anzahl der Portionen<\/strong>: 4<\/li>\n\n\n\n<li><strong>Schwierigkeitsgrad<\/strong>: einfach<\/li>\n<\/ul>\n\n\n\n<!--more-->\n\n\n\n<p>Auch im Sommer darf es manchmal etwas deftig sein\u2026 Brambor\u00e1ky werden in Tschechien gerne gef\u00fcllt serviert oder als Beilage zu Gulasch, herzhaften Eint\u00f6pfen oder mit einem leckeren Dip gegessen. Als Kind habe ich sie einfach mit Ketchup genascht. Da es beim Zubereiten auch ziemlich hei\u00df und geruchsintensiv werden kann, bereite ich sie gerne drau\u00dfen auf dem Lagerfeuer oder Grill in einer guten gusseisernen Pfanne zu.<\/p>\n\n\n\n<p>Damit sie besonders knusprig gelingen, mische ich den geriebenen Kartoffeln Sauerkraut bei und gehe nicht allzu sehr sparsam mit \u00d6l um. An die Pfanne, fertig, los!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Zutaten:<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1 kg Kartoffeln (vorwiegend festkochend)&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>500 g Sauerkraut<\/li>\n\n\n\n<li>3 Eier<\/li>\n\n\n\n<li>100 ml Milch<\/li>\n\n\n\n<li>200 g Mehl oder Semmelmehl<\/li>\n\n\n\n<li>1 TL Salz<\/li>\n\n\n\n<li>1 TL Majoran<\/li>\n\n\n\n<li>3-4 Knoblauchzehen (nach Geschmack)<\/li>\n\n\n\n<li>Pfeffer<\/li>\n\n\n\n<li>Evtl. K\u00fcmmel<\/li>\n\n\n\n<li>\u00d6l zum Braten<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Zubereitung:<\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Sauerkraut abgie\u00dfen und klein schneiden. <\/li>\n\n\n\n<li>Kartoffeln sch\u00e4len und fein reiben. Anschlie\u00dfend geriebene Kartoffeln in einem Tuch gut ausdr\u00fccken und mit Mehl, Eiern, Milch, Majoran, Salz, Pfeffer sowie gepresstem Knoblauch zu einem d\u00fcnnen Teig vermengen. <\/li>\n\n\n\n<li>In einer Pfanne reichlich \u00d6l erhitzen und aus einer kleinen Portion des Teigs mit einer Kelle einen \u201ebrambor\u00e1k\u201c (Kartoffelpuffer) formen. Dieser gelingt am besten, wenn er einen Durchmesser von ca. 10 cm hat und von beiden Seiten goldbraun gebraten wird<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\">Geheimtipps:<\/h3>\n\n\n\n<p>Bei einer guten Zucchiniernte kann auch eine fein geriebene Zucchini den Teig verfeinern.&nbsp;<br>Nach dem Braten die fertigen Puffer auf eine K\u00fcchenrolle legen, um das \u00fcberfl\u00fcssige Fett zu entfernen.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>F\u00fcr die Sommerwortschatztruhe<\/strong>:<\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Deutsch<\/th><th>Polnisch<\/th><th><em><strong>Aussprache<\/strong><\/em><\/th><th>Tschechisch<\/th><th><em><strong>Aussprache<\/strong><\/em><\/th><\/tr><\/thead><tbody><tr><td>Kartoffelpuffer<\/td><td>placki ziemniaczane<\/td><td><em><em><strong>pla<\/strong>zki dschemnja<strong>tscha<\/strong>ne<\/em><\/em><\/td><td>brambor\u00e1k<\/td><td><em><em><strong>bram<\/strong>boraak<\/em><\/em><\/td><\/tr><tr><td>knusprig<\/td><td>chrupi\u0105cy<\/td><td><em><em>chrup<strong>jon<\/strong>ze<\/em><\/em><\/td><td>k\u0159upav\u00fd<\/td><td><em><em><strong>krschu<\/strong>pavie<\/em><\/em><\/td><\/tr><tr><td>Sauerkraut<\/td><td>kiszona kapusta<\/td><td><em><em>kisch<strong>on<\/strong>e ka<strong>pu<\/strong>sta<\/em><\/em><\/td><td>kysel\u00e9 zel\u00ed<\/td><td><strong><em>k<\/em><\/strong><em><em><strong>i<\/strong>selee <strong>se<\/strong>lie<\/em><\/em><\/td><\/tr><tr><td>Knoblauch<\/td><td>czosnek<\/td><td><em><em><strong>tschoss<\/strong>nek<\/em><\/em><\/td><td>\u010desnek<\/td><td><em><em><strong>tsches<\/strong>neck<\/em><\/em><\/td><\/tr><tr><td>Pfanne<\/td><td>patelnia<\/td><td><em><em>pa<strong>tel<\/strong>nja<\/em><\/em><\/td><td>p\u00e1nev<\/td><td><em><em><strong>paa<\/strong>nef<\/em><\/em><\/td><\/tr><tr><td>Lagerfeuer<\/td><td>ognisko<\/td><td><em><em>og<strong>ni<\/strong>sko<\/em><\/em><\/td><td>t\u00e1bor\u00e1k<\/td><td><em><em><strong>taa<\/strong>boraack<\/em><\/em><\/td><\/tr><tr><td>Gulasch<\/td><td>gulasz<\/td><td><em><em><strong>gu<\/strong>lasch<\/em><\/em><\/td><td>gul\u00e1\u0161<\/td><td><em><em><strong>gu<\/strong>laasch<\/em><\/em><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Hier gibt es das Rezept zum Download und beliebigen Vervielf\u00e4ltigen: <a href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/de\/materialbibliothek.html#anc_685d0883cb6ca\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.nachbarsprachen-sachsen.eu\/de\/materialbibliothek.html#anc_685d0883cb6ca<\/a><\/strong><\/p>\n\n\n\n<p><strong>Guten Appetit \u2013 Smacznego \u2013 Dobrou chut\u00b4<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Getreu dem Motto \u201eSommer, Sonne, Ferien- und Urlaubszeit\u201c hat sich das Team der LaNa eine kleine Beitragsserie f\u00fcr die kommende Zeit ausgedacht: Wir stellen euch jede Woche ein unkompliziertes und obendrein sehr leckeres, sommerliches Rezept vor.Gedacht sind Speis und Trank f\u00fcr Klein bis Gro\u00df. Dar\u00fcber hinaus sind sie auf Tauglichkeit getestet, z. B. f\u00fcr die &hellip; <a href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/materialien\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html\" class=\"more-link\"><span class=\"screen-reader-text\">Lecker \u2013 Schmecker No.5: Sommerliche Rezepte aus der LaNa f\u00fcr Gartenfest &amp; Co., heute von unserer Kollegin Michaela<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,20,1007],"tags":[14,780,7,1940,1941,8,857],"class_list":["post-9450","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-lana-news","category-materialien","tag-deutsch","tag-dreilaenderregion","tag-polnisch","tag-rezepte","tag-sommerblog","tag-tschechisch","tag-wortschatz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lecker \u2013 Schmecker No.5: Sommerliche Rezepte aus der LaNa f\u00fcr Gartenfest &amp; Co., heute von unserer Kollegin Michaela - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung<\/title>\n<meta name=\"description\" content=\"LaNa stellt leckere, unkomplizierte und sommerliche Rezepte vor: Auf die L\u00f6ffel, fertig, ran an die T\u00f6pfe!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lecker \u2013 Schmecker No.5: Sommerliche Rezepte aus der LaNa f\u00fcr Gartenfest &amp; Co., heute von unserer Kollegin Michaela - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\" \/>\n<meta property=\"og:description\" content=\"LaNa stellt leckere, unkomplizierte und sommerliche Rezepte vor: Auf die L\u00f6ffel, fertig, ran an die T\u00f6pfe!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html\" \/>\n<meta property=\"og:site_name\" content=\"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-30T07:07:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T13:25:44+00:00\" \/>\n<meta name=\"author\" content=\"LaNa-Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"LaNa-Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html\"},\"author\":{\"name\":\"LaNa-Team\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2\"},\"headline\":\"Lecker \u2013 Schmecker No.5: Sommerliche Rezepte aus der LaNa f\u00fcr Gartenfest &amp; Co., heute von unserer Kollegin Michaela\",\"datePublished\":\"2025-07-30T07:07:56+00:00\",\"dateModified\":\"2026-05-05T13:25:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html\"},\"wordCount\":483,\"commentCount\":1,\"keywords\":[\"Deutsch\",\"Dreil\u00e4nderregion\",\"Polnisch\",\"Rezepte\",\"Sommerblog\",\"Tschechisch\",\"Wortschatz\"],\"articleSection\":{\"1\":\"LaNa News\",\"2\":\"Materialien\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html\",\"url\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html\",\"name\":\"Lecker \u2013 Schmecker No.5: Sommerliche Rezepte aus der LaNa f\u00fcr Gartenfest &amp; Co., heute von unserer Kollegin Michaela - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\",\"isPartOf\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website\"},\"datePublished\":\"2025-07-30T07:07:56+00:00\",\"dateModified\":\"2026-05-05T13:25:44+00:00\",\"author\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2\"},\"description\":\"LaNa stellt leckere, unkomplizierte und sommerliche Rezepte vor: Auf die L\u00f6ffel, fertig, ran an die T\u00f6pfe!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lecker \u2013 Schmecker No.5: Sommerliche Rezepte aus der LaNa f\u00fcr Gartenfest &amp; Co., heute von unserer Kollegin Michaela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website\",\"url\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/\",\"name\":\"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\",\"description\":\"Nachbarsprache von Anfang an!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2\",\"name\":\"LaNa-Team\",\"url\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/author\/ikp-redakteur_ab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lecker \u2013 Schmecker No.5: Sommerliche Rezepte aus der LaNa f\u00fcr Gartenfest &amp; Co., heute von unserer Kollegin Michaela - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","description":"LaNa stellt leckere, unkomplizierte und sommerliche Rezepte vor: Auf die L\u00f6ffel, fertig, ran an die T\u00f6pfe!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html","og_locale":"de_DE","og_type":"article","og_title":"Lecker \u2013 Schmecker No.5: Sommerliche Rezepte aus der LaNa f\u00fcr Gartenfest &amp; Co., heute von unserer Kollegin Michaela - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","og_description":"LaNa stellt leckere, unkomplizierte und sommerliche Rezepte vor: Auf die L\u00f6ffel, fertig, ran an die T\u00f6pfe!","og_url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html","og_site_name":"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","article_published_time":"2025-07-30T07:07:56+00:00","article_modified_time":"2026-05-05T13:25:44+00:00","author":"LaNa-Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"LaNa-Team","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html#article","isPartOf":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html"},"author":{"name":"LaNa-Team","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2"},"headline":"Lecker \u2013 Schmecker No.5: Sommerliche Rezepte aus der LaNa f\u00fcr Gartenfest &amp; Co., heute von unserer Kollegin Michaela","datePublished":"2025-07-30T07:07:56+00:00","dateModified":"2026-05-05T13:25:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html"},"wordCount":483,"commentCount":1,"keywords":["Deutsch","Dreil\u00e4nderregion","Polnisch","Rezepte","Sommerblog","Tschechisch","Wortschatz"],"articleSection":{"1":"LaNa News","2":"Materialien"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html","name":"Lecker \u2013 Schmecker No.5: Sommerliche Rezepte aus der LaNa f\u00fcr Gartenfest &amp; Co., heute von unserer Kollegin Michaela - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","isPartOf":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website"},"datePublished":"2025-07-30T07:07:56+00:00","dateModified":"2026-05-05T13:25:44+00:00","author":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2"},"description":"LaNa stellt leckere, unkomplizierte und sommerliche Rezepte vor: Auf die L\u00f6ffel, fertig, ran an die T\u00f6pfe!","breadcrumb":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lecker-schmecker-no-5-sommerliche-rezepte-aus-der-lana-fuer-gartenfest-co.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog"},{"@type":"ListItem","position":2,"name":"Lecker \u2013 Schmecker No.5: Sommerliche Rezepte aus der LaNa f\u00fcr Gartenfest &amp; Co., heute von unserer Kollegin Michaela"}]},{"@type":"WebSite","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/","name":"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","description":"Nachbarsprache von Anfang an!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2","name":"LaNa-Team","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/author\/ikp-redakteur_ab"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts\/9450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/comments?post=9450"}],"version-history":[{"count":8,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts\/9450\/revisions"}],"predecessor-version":[{"id":9557,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts\/9450\/revisions\/9557"}],"wp:attachment":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/media?parent=9450"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/categories?post=9450"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/tags?post=9450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}