{"id":9049,"date":"2024-12-09T09:07:24","date_gmt":"2024-12-09T08:07:24","guid":{"rendered":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/?p=9049"},"modified":"2026-05-05T10:49:39","modified_gmt":"2026-05-05T08:49:39","slug":"lana-netzwerkt-trinational","status":"publish","type":"post","link":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html","title":{"rendered":"LaNa netzwerkt trinational \u2026"},"content":{"rendered":"\n<p>\u2026 und das gleich auf zwei aufeinanderfolgenden wichtigen grenz\u00fcberschreitenden Netzwerkveranstaltungen im November:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>21.\/22.11.2024: 2. Deutsch-Tschechisches Regionalforum r\u00fcckt grenz\u00fcberschreitende Regionen weiter in den Fokus der Politik<\/strong><\/h3>\n\n\n\n<p>Einen von insgesamt drei Schwerpunkten der vom <a href=\"https:\/\/www.auswaertiges-amt.de\/de\" target=\"_blank\" rel=\"noreferrer noopener\">Ausw\u00e4rtigen Amt<\/a> organisierten Veranstaltung bildete dabei das Thema Sprache in der grenz\u00fcberschreitenden deutsch-tschechischen Region. Dies war das Ergebnis der vorangegangenen Veranstaltung 2023 in Chemnitz, wo die \u00dcberwindung der Sprachbarrieren und das Fehlen ganzheitlicher, fl\u00e4chendeckender und kontinuierlicher nachbarsprachiger Bildung als eine ressort\u00fcbergreifende Herausforderung identifiziert wurde. In enger Zusammenarbeit mit der LaNa konnte sich in Liberec nun ein zweit\u00e4giger Workshop \u201eChance Grenzregion: Zwei Sprachen \u2013 zwei Kulturen \u2013 eine gemeinsame Region. Nachbarsprachige Bildung im deutsch-tschechischen Grenzraum &#8220; explizit der Erarbeitung von konkreten L\u00f6sungsvorschl\u00e4gen und Denkimpulsen, die (nicht nur) an Akteure nationaler Politik gerichtet werden, widmen. \u00a0<\/p>\n\n\n\n<p>Mehr Informationen finden Sie in K\u00fcrze auf den Internetseiten des Ausw\u00e4rtigen Amtes der Bundesrepublik Deutschland unter <a href=\"https:\/\/www.auswaertiges-amt.de\/de\/aussenpolitik\/europa\/zusammenarbeit-staaten\">https:\/\/www.auswaertiges-amt.de\/de\/aussenpolitik\/europa\/zusammenarbeit-staaten<\/a><\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\"><strong>28.\/29.11.2024: 2. Trinationale Vernetzungstagung der Europaakteure aus Sachsen, Polen und Tschechien diskutiert Ans\u00e4tze der Europabildung<\/strong><\/h3>\n\n\n\n<p>Am 28.11.2024 trafen sich das Netzwerk s\u00e4chsischer Akteure der Europabildung in der S\u00e4chsischen Landeszentrale f\u00fcr politische Bildung. Hier stand zun\u00e4chst der Austausch zu einem gemeinsamen Kurs der Europabildnerinnen und -bildner in herausfordernden Zeiten im Mittelpunkt. Im Anschluss fand die 2. Trinationale Vernetzungstagung mit Einrichtungen der Europabildung aus Polen und Tschechien statt. Zentrum dieser Veranstaltung war das St\u00e4rken des Netzwerkes und das Sichtbarmachen guter Praxis, um sich den gegenw\u00e4rtigen Herausforderungen im \u201egemeinsamen europ\u00e4ischen Haus\u201c auch gemeinsam zu stellen. Neben interaktiven Workshops und interessanten Podiumsdiskussionen gab es deshalb viel Raum f\u00fcr den Austausch von Erfahrungen und Best-Practice-Beispielen.<\/p>\n\n\n\n<p>Mehr Informationen finden Sie in K\u00fcrze bei den Veranstaltenden: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.slpb.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">S\u00e4chsische Landeszentrale f\u00fcr politische Bildung<\/a> <\/li>\n\n\n\n<li><a href=\"https:\/\/www.eao-otzenhausen.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Europ\u00e4ische Akademie Otzenhausen<\/a>  <\/li>\n\n\n\n<li><a href=\"https:\/\/www.justiz.sachsen.de\/smj\/\" target=\"_blank\" rel=\"noreferrer noopener\">S\u00e4chsische<\/a>s<a href=\"https:\/\/www.justiz.sachsen.de\/smj\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Staatsministerium der Justiz und f\u00fcr Demokratie, Europa und Gleichstellung<\/a><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fazit f\u00fcr uns als LaNa aus diesen intensiven Veranstaltungstagen <\/strong><\/h3>\n\n\n\n<p>Der pers\u00f6nliche und regelm\u00e4\u00dfige Austausch auf Augenh\u00f6he und im gemeinsamen Miteinander ist wertvoll f\u00fcr das Netzwerk insgesamt und f\u00fcr die jeweilige Praxis des Einzelnen ein Zugewinn. Wir freuen uns auf den weiteren gemeinsamen Diskurs und gemeinsame Aktivit\u00e4ten. \u00a0\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2026 und das gleich auf zwei aufeinanderfolgenden wichtigen grenz\u00fcberschreitenden Netzwerkveranstaltungen im November: 21.\/22.11.2024: 2. Deutsch-Tschechisches Regionalforum r\u00fcckt grenz\u00fcberschreitende Regionen weiter in den Fokus der Politik Einen von insgesamt drei Schwerpunkten der vom Ausw\u00e4rtigen Amt organisierten Veranstaltung bildete dabei das Thema Sprache in der grenz\u00fcberschreitenden deutsch-tschechischen Region. Dies war das Ergebnis der vorangegangenen Veranstaltung 2023 in &hellip; <a href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html\" class=\"more-link\"><span class=\"screen-reader-text\">LaNa netzwerkt trinational \u2026<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":9055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,20,46,42],"tags":[1866,185,1683,1867,6,1076,380,1862,839],"class_list":["post-9049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-lana-news","category-stimmen-aus-der-praxis","category-veranstaltungen","tag-binational","tag-deutsch-tschechisch","tag-europabildung","tag-konzept-europabildung-sachsen","tag-nachbarsprache","tag-nachbarsprachige-bildung","tag-netzwerk","tag-nl4-24","tag-trinational"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LaNa netzwerkt trinational \u2026 - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LaNa netzwerkt trinational \u2026 - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\" \/>\n<meta property=\"og:description\" content=\"\u2026 und das gleich auf zwei aufeinanderfolgenden wichtigen grenz\u00fcberschreitenden Netzwerkveranstaltungen im November: 21.\/22.11.2024: 2. Deutsch-Tschechisches Regionalforum r\u00fcckt grenz\u00fcberschreitende Regionen weiter in den Fokus der Politik Einen von insgesamt drei Schwerpunkten der vom Ausw\u00e4rtigen Amt organisierten Veranstaltung bildete dabei das Thema Sprache in der grenz\u00fcberschreitenden deutsch-tschechischen Region. Dies war das Ergebnis der vorangegangenen Veranstaltung 2023 in &hellip; LaNa netzwerkt trinational \u2026 weiterlesen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html\" \/>\n<meta property=\"og:site_name\" content=\"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-09T08:07:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-05T08:49:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2024\/12\/foto_blog-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"876\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"LaNa-Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"LaNa-Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html\"},\"author\":{\"name\":\"LaNa-Team\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2\"},\"headline\":\"LaNa netzwerkt trinational \u2026\",\"datePublished\":\"2024-12-09T08:07:24+00:00\",\"dateModified\":\"2026-05-05T08:49:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html\"},\"wordCount\":358,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2024\/12\/foto_blog-1.jpg\",\"keywords\":[\"binational\",\"deutsch-tschechisch\",\"Europabildung\",\"Konzept Europabildung Sachsen\",\"Nachbarsprache\",\"nachbarsprachige Bildung\",\"Netzwerk\",\"NL4-24\",\"trinational\"],\"articleSection\":{\"1\":\"LaNa News\",\"2\":\"Stimmen aus der Praxis\",\"3\":\"Veranstaltungen\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html\",\"url\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html\",\"name\":\"LaNa netzwerkt trinational \u2026 - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\",\"isPartOf\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2024\/12\/foto_blog-1.jpg\",\"datePublished\":\"2024-12-09T08:07:24+00:00\",\"dateModified\":\"2026-05-05T08:49:39+00:00\",\"author\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#primaryimage\",\"url\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2024\/12\/foto_blog-1.jpg\",\"contentUrl\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2024\/12\/foto_blog-1.jpg\",\"width\":876,\"height\":701},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LaNa netzwerkt trinational \u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website\",\"url\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/\",\"name\":\"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\",\"description\":\"Nachbarsprache von Anfang an!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2\",\"name\":\"LaNa-Team\",\"url\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/author\/ikp-redakteur_ab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LaNa netzwerkt trinational \u2026 - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html","og_locale":"de_DE","og_type":"article","og_title":"LaNa netzwerkt trinational \u2026 - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","og_description":"\u2026 und das gleich auf zwei aufeinanderfolgenden wichtigen grenz\u00fcberschreitenden Netzwerkveranstaltungen im November: 21.\/22.11.2024: 2. Deutsch-Tschechisches Regionalforum r\u00fcckt grenz\u00fcberschreitende Regionen weiter in den Fokus der Politik Einen von insgesamt drei Schwerpunkten der vom Ausw\u00e4rtigen Amt organisierten Veranstaltung bildete dabei das Thema Sprache in der grenz\u00fcberschreitenden deutsch-tschechischen Region. Dies war das Ergebnis der vorangegangenen Veranstaltung 2023 in &hellip; LaNa netzwerkt trinational \u2026 weiterlesen","og_url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html","og_site_name":"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","article_published_time":"2024-12-09T08:07:24+00:00","article_modified_time":"2026-05-05T08:49:39+00:00","og_image":[{"width":876,"height":701,"url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2024\/12\/foto_blog-1.jpg","type":"image\/jpeg"}],"author":"LaNa-Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"LaNa-Team","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#article","isPartOf":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html"},"author":{"name":"LaNa-Team","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2"},"headline":"LaNa netzwerkt trinational \u2026","datePublished":"2024-12-09T08:07:24+00:00","dateModified":"2026-05-05T08:49:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html"},"wordCount":358,"commentCount":0,"image":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#primaryimage"},"thumbnailUrl":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2024\/12\/foto_blog-1.jpg","keywords":["binational","deutsch-tschechisch","Europabildung","Konzept Europabildung Sachsen","Nachbarsprache","nachbarsprachige Bildung","Netzwerk","NL4-24","trinational"],"articleSection":{"1":"LaNa News","2":"Stimmen aus der Praxis","3":"Veranstaltungen"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html","name":"LaNa netzwerkt trinational \u2026 - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","isPartOf":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#primaryimage"},"image":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#primaryimage"},"thumbnailUrl":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2024\/12\/foto_blog-1.jpg","datePublished":"2024-12-09T08:07:24+00:00","dateModified":"2026-05-05T08:49:39+00:00","author":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2"},"breadcrumb":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#primaryimage","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2024\/12\/foto_blog-1.jpg","contentUrl":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2024\/12\/foto_blog-1.jpg","width":876,"height":701},{"@type":"BreadcrumbList","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/allgemein\/lana-netzwerkt-trinational.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog"},{"@type":"ListItem","position":2,"name":"LaNa netzwerkt trinational \u2026"}]},{"@type":"WebSite","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/","name":"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","description":"Nachbarsprache von Anfang an!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2","name":"LaNa-Team","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/author\/ikp-redakteur_ab"}]}},"jetpack_featured_media_url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-content\/uploads\/2024\/12\/foto_blog-1.jpg","_links":{"self":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts\/9049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/comments?post=9049"}],"version-history":[{"count":2,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts\/9049\/revisions"}],"predecessor-version":[{"id":9053,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts\/9049\/revisions\/9053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/media\/9055"}],"wp:attachment":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/media?parent=9049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/categories?post=9049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/tags?post=9049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}