{"id":8411,"date":"2024-01-03T09:05:00","date_gmt":"2024-01-03T08:05:00","guid":{"rendered":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/?p=8411"},"modified":"2026-05-03T09:08:15","modified_gmt":"2026-05-03T07:08:15","slug":"zum-beginn-des-neuen-jahres","status":"publish","type":"post","link":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html","title":{"rendered":"Zum Beginn des neuen Jahres"},"content":{"rendered":"\n<p>Wir hoffen, dass Sie den warmen Glanz der zur\u00fcckliegenden Festtage noch im Herzen tragen und gesund und gl\u00fccklich das neue Jahr begr\u00fc\u00dfen konnten.<br>Das <a href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/de\/unser-team.html\">Team <\/a>der <a href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/de\/ueber-uns.html\">S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung<\/a> w\u00fcnscht Ihnen allen von Herzen ein gesundes, hoffnungsvolles sowie friedliches 2024. Wir freuen uns darauf, an bestehende Kooperationen und gute Zusammenarbeit anzukn\u00fcpfen. Ebenso freuen wir uns darauf, neue Wege f\u00fcr die nachbarsprachige Bildung in den s\u00e4chsischen Euroregionen mit vertrauten sowie neuen Partnerinnen und Partnern (nicht nur) in Sachsen, Polen und Tschechien zu gehen.<\/p>\n\n\n\n<!--more-->\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Den dreisprachiger Kalender 2024 im Blick behalten<\/strong><\/h3>\n\n\n\n<p>Auch f\u00fcr 2024 hat die LaNa f\u00fcr Sie und unsere Nachbarinnen und Nachbarn in Polen und Tschechien eine dreisprachige \u00dcbersicht aller Termine in unserer gemeinsamen Dreil\u00e4nderregion vorbereitet. Der <a href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/de\/jahreskalender-2024.html\">Kalender 2024 steht Ihnen kostenlos zum Herunterladen<\/a> in der <a href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/materialbibliothek\">Materialbibliothek <\/a>zur Verf\u00fcgung. Auf Anfrage erhalten Sie auch noch wenige Exemplare als Poster bei uns \u2013 selbstverst\u00e4ndlich nur, solange der Vorrat reicht. <a href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/de\/kontakt.html\">Kontaktieren Sie uns gern.<\/a><\/p>\n\n\n\n<p><strong>\u00dcbrigens<\/strong>: Auch auf die Landesstelle Nachbarsprachen warten in diesem Jahr so manch\u2018 besondere H\u00f6hepunkte, die wir gemeinsam mit Ihnen feiern m\u00f6chten. So sind wir z. B. um den 1. Mai dabei bei den gemeinsamen Feierlichkeiten rund um das 20j\u00e4hrige Jubil\u00e4um des EU-Beitritts unserer Nachbarl\u00e4nder Polen und Tschechien. Au\u00dferdem wartet im September ein eigenes Jubil\u00e4um auf uns \u2013 wir feier unser 10j\u00e4hriges Bestehen. Seien Sie gespannt darauf und merken sich dies gern schon vor!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir hoffen, dass Sie den warmen Glanz der zur\u00fcckliegenden Festtage noch im Herzen tragen und gesund und gl\u00fccklich das neue Jahr begr\u00fc\u00dfen konnten.Das Team der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung w\u00fcnscht Ihnen allen von Herzen ein gesundes, hoffnungsvolles sowie friedliches 2024. Wir freuen uns darauf, an bestehende Kooperationen und gute Zusammenarbeit anzukn\u00fcpfen. Ebenso freuen wir &hellip; <a href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html\" class=\"more-link\"><span class=\"screen-reader-text\">Zum Beginn des neuen Jahres<\/span> weiterlesen<\/a><\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,20],"tags":[1723,1721,1722],"class_list":["post-8411","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-lana-news","tag-1723","tag-jahresanfang","tag-neujahr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zum Beginn des neuen Jahres - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung<\/title>\n<meta name=\"description\" content=\"Die LaNa w\u00fcnscht allen ein gesundes und gl\u00fcckliches neues Jahr, empfielt ihren dreisprachigen Kalender und H\u00f6hepunkte in 2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zum Beginn des neuen Jahres - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\" \/>\n<meta property=\"og:description\" content=\"Die LaNa w\u00fcnscht allen ein gesundes und gl\u00fcckliches neues Jahr, empfielt ihren dreisprachigen Kalender und H\u00f6hepunkte in 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html\" \/>\n<meta property=\"og:site_name\" content=\"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-03T08:05:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-03T07:08:15+00:00\" \/>\n<meta name=\"author\" content=\"LaNa-Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"LaNa-Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html\"},\"author\":{\"name\":\"LaNa-Team\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2\"},\"headline\":\"Zum Beginn des neuen Jahres\",\"datePublished\":\"2024-01-03T08:05:00+00:00\",\"dateModified\":\"2026-05-03T07:08:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html\"},\"wordCount\":247,\"commentCount\":0,\"keywords\":[\"2024\",\"Jahresanfang\",\"Neujahr\"],\"articleSection\":{\"1\":\"LaNa News\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html\",\"url\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html\",\"name\":\"Zum Beginn des neuen Jahres - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\",\"isPartOf\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website\"},\"datePublished\":\"2024-01-03T08:05:00+00:00\",\"dateModified\":\"2026-05-03T07:08:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2\"},\"description\":\"Die LaNa w\u00fcnscht allen ein gesundes und gl\u00fcckliches neues Jahr, empfielt ihren dreisprachigen Kalender und H\u00f6hepunkte in 2024.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zum Beginn des neuen Jahres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website\",\"url\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/\",\"name\":\"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung\",\"description\":\"Nachbarsprache von Anfang an!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2\",\"name\":\"LaNa-Team\",\"url\":\"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/author\/ikp-redakteur_ab\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zum Beginn des neuen Jahres - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","description":"Die LaNa w\u00fcnscht allen ein gesundes und gl\u00fcckliches neues Jahr, empfielt ihren dreisprachigen Kalender und H\u00f6hepunkte in 2024.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html","og_locale":"de_DE","og_type":"article","og_title":"Zum Beginn des neuen Jahres - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","og_description":"Die LaNa w\u00fcnscht allen ein gesundes und gl\u00fcckliches neues Jahr, empfielt ihren dreisprachigen Kalender und H\u00f6hepunkte in 2024.","og_url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html","og_site_name":"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","article_published_time":"2024-01-03T08:05:00+00:00","article_modified_time":"2026-05-03T07:08:15+00:00","author":"LaNa-Team","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"LaNa-Team","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html#article","isPartOf":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html"},"author":{"name":"LaNa-Team","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2"},"headline":"Zum Beginn des neuen Jahres","datePublished":"2024-01-03T08:05:00+00:00","dateModified":"2026-05-03T07:08:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html"},"wordCount":247,"commentCount":0,"keywords":["2024","Jahresanfang","Neujahr"],"articleSection":{"1":"LaNa News"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html","name":"Zum Beginn des neuen Jahres - Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","isPartOf":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website"},"datePublished":"2024-01-03T08:05:00+00:00","dateModified":"2026-05-03T07:08:15+00:00","author":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2"},"description":"Die LaNa w\u00fcnscht allen ein gesundes und gl\u00fcckliches neues Jahr, empfielt ihren dreisprachigen Kalender und H\u00f6hepunkte in 2024.","breadcrumb":{"@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/lana-news\/zum-beginn-des-neuen-jahres.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog"},{"@type":"ListItem","position":2,"name":"Zum Beginn des neuen Jahres"}]},{"@type":"WebSite","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#website","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/","name":"Blog der S\u00e4chsischen Landesstelle f\u00fcr nachbarsprachige Bildung","description":"Nachbarsprache von Anfang an!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/#\/schema\/person\/13239f936c7ffee5b60975f82a2531a2","name":"LaNa-Team","url":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/author\/ikp-redakteur_ab"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts\/8411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/comments?post=8411"}],"version-history":[{"count":2,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts\/8411\/revisions"}],"predecessor-version":[{"id":8415,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/posts\/8411\/revisions\/8415"}],"wp:attachment":[{"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/media?parent=8411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/categories?post=8411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nachbarsprachen-sachsen.eu\/lana\/blog\/wp-json\/wp\/v2\/tags?post=8411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}